{"id":9,"date":"2021-12-10T00:42:48","date_gmt":"2021-12-10T00:42:48","guid":{"rendered":"https:\/\/www.dms-petsitting.com\/PS-2\/index.php\/services\/"},"modified":"2025-06-30T16:39:06","modified_gmt":"2025-06-30T16:39:06","slug":"services","status":"publish","type":"page","link":"http:\/\/www.dms-petsitting.com\/PS-2\/services\/","title":{"rendered":"Services"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"9\" class=\"elementor elementor-9\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1b5d07b7 elementor-section-height-min-height elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-id=\"1b5d07b7\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-27b2267d\" data-id=\"27b2267d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7d201e88 elementor-widget elementor-widget-heading\" data-id=\"7d201e88\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Business Name<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-734b7c97 elementor-widget elementor-widget-heading\" data-id=\"734b7c97\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pet Sitting and Dog Walking Services<br>(000) 000-0000<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3f0fcb8c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3f0fcb8c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5ca86d40\" data-id=\"5ca86d40\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f913b72 elementor-widget elementor-widget-heading\" data-id=\"f913b72\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Services Areas:  Area 1 Area 2   Area 3  Area 4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7cbe6cf6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7cbe6cf6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-7549f6e4\" data-id=\"7549f6e4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66769896 elementor-widget elementor-widget-heading\" data-id=\"66769896\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Services<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a484024 elementor-widget elementor-widget-image\" data-id=\"6a484024\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"343\" src=\"http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/uploads\/2021\/12\/shutterstock_64538062.jpg\" class=\"attachment-large size-large wp-image-11\" alt=\"\" srcset=\"http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/uploads\/2021\/12\/shutterstock_64538062.jpg 500w, http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/uploads\/2021\/12\/shutterstock_64538062-300x206.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4067ee26 elementor-widget elementor-widget-text-editor\" data-id=\"4067ee26\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Provide company for your pet(s), even taking them outside to play.<\/li><li>Feed and give the pet fresh water.<\/li><li>Take the dog for a walk outside for exercise.<\/li><li>Spend cuddle time as needed with dogs, cats, and other critters.<\/li><li>Clean litter boxes and clean up any other pet mess that may occur.<\/li><li>Depending on the pet, we can administer medications if required.<\/li><li>Take your pet to their vet or grooming appointments.<\/li><li>If you are away for an extended period of time, we can bring in mail, put out the trash bins, water plants, and house sit.<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-2bbf41b6\" data-id=\"2bbf41b6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6911c4f7 elementor-widget elementor-widget-heading\" data-id=\"6911c4f7\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Our Pricing<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2ad60bc9 elementor-widget elementor-widget-image\" data-id=\"2ad60bc9\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1000\" height=\"667\" src=\"http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/uploads\/2021\/12\/shutterstock_374801014.jpg\" class=\"attachment-large size-large wp-image-12\" alt=\"\" srcset=\"http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/uploads\/2021\/12\/shutterstock_374801014.jpg 1000w, http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/uploads\/2021\/12\/shutterstock_374801014-300x200.jpg 300w, http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/uploads\/2021\/12\/shutterstock_374801014-768x512.jpg 768w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4899be7a elementor-widget elementor-widget-text-editor\" data-id=\"4899be7a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<ul><li>Dog \/ Pet Walking:\u00a0 $20.00 per visit (30 minutes)<\/li><li>Power Visit (cats, birds, etc.) 15 minutes $17.50<\/li><li>Overnight stay:\u00a0 $65.00<\/li><li>Pet Taxi to Vet or Groomer:\u00a0 As quoted<\/li><li>House Sitting:\u00a0 Custom quote (call)<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-3ac88c26\" data-id=\"3ac88c26\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-731bd87d elementor-widget elementor-widget-heading\" data-id=\"731bd87d\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact Us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bf94968 elementor-widget elementor-widget-wpforms\" data-id=\"bf94968\" data-element_type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-382\"><form id=\"wpforms-form-382\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"382\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/PS-2\/wp-json\/wp\/v2\/pages\/9\" data-token=\"82cb627ee0f684fe561a37d3e38eab23\" data-token-time=\"1788337481\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-382-field_1-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-382-field_1\">Your Name<\/label><input type=\"text\" id=\"wpforms-382-field_1\" class=\"wpforms-field-medium\" name=\"wpforms[fields][1]\" ><\/div><div id=\"wpforms-382-field_2-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-382-field_2\">Contact Phone<\/label><input type=\"text\" id=\"wpforms-382-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" ><\/div><div id=\"wpforms-382-field_3-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-382-field_3\">Contact Email<\/label><input type=\"text\" id=\"wpforms-382-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" ><\/div><div id=\"wpforms-382-field_5-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"5\"><label class=\"wpforms-field-label\">Type of Service Needed<\/label><ul id=\"wpforms-382-field_5\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-382-field_5_1\" name=\"wpforms[fields][5][]\" value=\"Dog Walking\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-382-field_5_1\">Dog Walking<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-382-field_5_2\" name=\"wpforms[fields][5][]\" value=\"Pet Sitting\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-382-field_5_2\">Pet Sitting<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-382-field_5_3\" name=\"wpforms[fields][5][]\" value=\"Pet Taxi\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-382-field_5_3\">Pet Taxi<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-382-field_5_4\" name=\"wpforms[fields][5][]\" value=\"House Sitting\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-382-field_5_4\">House Sitting<\/label><\/li><li class=\"choice-5 depth-1\"><input type=\"checkbox\" id=\"wpforms-382-field_5_5\" name=\"wpforms[fields][5][]\" value=\"Other Service\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-382-field_5_5\">Other Service<\/label><\/li><\/ul><\/div><div id=\"wpforms-382-field_6-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-382-field_6\">Tell us more about your pets<\/label><textarea id=\"wpforms-382-field_6\" class=\"wpforms-field-medium\" name=\"wpforms[fields][6]\" ><\/textarea><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"382\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"http:\/\/www.dms-petsitting.com\/PS-2\/wp-json\/wp\/v2\/pages\/9\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-382\" class=\"wpforms-submit\" data-alt-text=\"Sending...\" data-submit-text=\"Submit\" aria-live=\"assertive\" value=\"wpforms-submit\">Submit<\/button><img decoding=\"async\" src=\"http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Loading\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61b2bbd8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61b2bbd8\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-322e4856\" data-id=\"322e4856\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22583107 elementor-widget elementor-widget-image\" data-id=\"22583107\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"393\" src=\"http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/uploads\/2021\/12\/400px-Call_Us_Bird.jpg\" class=\"attachment-large size-large wp-image-13\" alt=\"\" srcset=\"http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/uploads\/2021\/12\/400px-Call_Us_Bird.jpg 400w, http:\/\/www.dms-petsitting.com\/PS-2\/wp-content\/uploads\/2021\/12\/400px-Call_Us_Bird-300x295.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6f1c0636\" data-id=\"6f1c0636\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9284a1e elementor-widget elementor-widget-heading\" data-id=\"9284a1e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Contact Us<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22a0b46b elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"22a0b46b\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-paw\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Call:  Owner \/ Operator name<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-paw\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mailing Address 1<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-paw\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Mailing Address 2<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-paw\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">City, State, Zip<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-paw\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Office Ph:  (000) 000-0000<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-paw\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">After Hours Cell:<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-paw\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Email:  Email Address<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Business Name Pet Sitting and Dog Walking Services(000) 000-0000 Our Services Areas: Area 1 Area 2 Area 3 Area 4 Our Services Provide company for your pet(s), even taking them outside to play. Feed and give the pet fresh water. Take the dog for a walk outside for exercise. Spend cuddle time as needed with [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"site-sidebar-layout":"no-sidebar","site-content-layout":"page-builder","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"disabled","ast-breadcrumbs-content":"","ast-featured-img":"disabled","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-9","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"http:\/\/www.dms-petsitting.com\/PS-2\/wp-json\/wp\/v2\/pages\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.dms-petsitting.com\/PS-2\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.dms-petsitting.com\/PS-2\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.dms-petsitting.com\/PS-2\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.dms-petsitting.com\/PS-2\/wp-json\/wp\/v2\/comments?post=9"}],"version-history":[{"count":20,"href":"http:\/\/www.dms-petsitting.com\/PS-2\/wp-json\/wp\/v2\/pages\/9\/revisions"}],"predecessor-version":[{"id":394,"href":"http:\/\/www.dms-petsitting.com\/PS-2\/wp-json\/wp\/v2\/pages\/9\/revisions\/394"}],"wp:attachment":[{"href":"http:\/\/www.dms-petsitting.com\/PS-2\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}